{"id":126316,"date":"2024-10-02T21:52:05","date_gmt":"2024-10-02T19:52:05","guid":{"rendered":"http:\/\/arosmarmitte.it\/prodotto\/uncategorized\/collettore-4-2-1-con-catalizzatore-8\/"},"modified":"2024-10-02T21:52:07","modified_gmt":"2024-10-02T19:52:07","slug":"collettore-4-2-1-con-catalizzatore-8","status":"publish","type":"product","link":"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/","title":{"rendered":"Collettore 4-2-1 con catalizzatore"},"content":{"rendered":"<p>Il collettore \u00e8 una parte fondamentale del sistema di scarico dell&#8217;auto in quanto \u00e8 il primo elemento che permette ai gas di evacuare dalla camera di scoppio, quindi l&#8217;installazione in vettura di un collettore dimensionato ad hoc e con spirito sportivo, consente di incrementare abbastanza agevolmente le prestazioni del motore. In questo caso la conformazione del collettore \u00e8 del tipo 4-2-1 con lunghezza uguale dei tubi e al banco \u00e8 stato possibile verificare un aumento delle prestazioni di circa 16 cv.<br \/>\nIl materiale utilizzato per la realizzazione \u00e8 l&#8217;acciaio AISI 304 e le saldature, al fine di assicurare la massima tenuta e resistenza, sono realizzate solamente a TIG dalle mani esperte dei nostri operatori mentre l&#8217;impiego di tubi con spessori ridotti, generalmente 1.2 mm, mettono in risalto ulteriormente l\u2019elevato livello di qualit\u00e0 e un\u2019attenzione oculata ai pesi, ne deriva che l&#8217;unione di queste attenzioni costruttive danno al collettore la caratteristica fondamentale di essere notevolmente leggero e resistente alle sollecitazioni oltre che estremamente performante dal punto di vista prestazionale. Le flange sono prodotte tramite macchinari a controllo numerico\/taglio a laser, con forature di assoluta precisione, per assicurare un montaggio perfetto e garantire la resistenza ottimale alle elevate temperature a cui sono sottoposte.<br \/>\nIl prodotto \u00e8 plug&#038;play e il posizionamento e la sequenza dei sensori \u00e8 compatibile con gli originali per garantire il perfetto funzionamento del motore, da notare che la sostituzione del collettore originale non comporta alcuna modifica del sistema di gestione elettronica essendo integrato un catalizzatore metallico da 200 celle.<br \/>\nInfine ci teniamo a sottolineare che progettazione, sviluppo, realizzazione e produzione sono operazioni svolte esclusivamente all&#8217;interno della nostra sede e il prodotto gode di tutte le caratteristiche e cure della migliore tradizione artigianale italiana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il collettore \u00e8 una parte fondamentale del sistema di scarico dell&#8217;auto in quanto \u00e8 il primo elemento che permette ai gas di evacuare dalla camera di scoppio, quindi l&#8217;installazione in vettura di un collettore dimensionato ad hoc e con spirito sportivo, consente di incrementare abbastanza agevolmente le prestazioni del motore. In questo caso la conformazione [&hellip;]<\/p>\n","protected":false},"featured_media":111943,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"marca":[],"product_brand":[],"product_cat":[655],"product_tag":[],"class_list":{"0":"post-126316","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-exhaust-systems","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.8 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Collettore 4-2-1 con catalizzatore | Aros Marmitte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collettore 4-2-1 con catalizzatore\" \/>\n<meta property=\"og:description\" content=\"Il collettore \u00e8 una parte fondamentale del sistema di scarico dell&#8217;auto in quanto \u00e8 il primo elemento che permette ai gas di evacuare dalla camera di scoppio, quindi l&#8217;installazione in vettura di un collettore dimensionato ad hoc e con spirito sportivo, consente di incrementare abbastanza agevolmente le prestazioni del motore. In questo caso la conformazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/\" \/>\n<meta property=\"og:site_name\" content=\"Aros Marmitte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arosmarmitte\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-02T19:52:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arosmarmitte.it\/wp-content\/uploads\/Collettore-di-scarico-4-2-1-con-catalizzatore-per-subaru-brz-toyota-GT86-manifold-headers-catalyst-exhuast-system-sound-echappement-marmitta-scarico-artigianale-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1093\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AROS_MARMITTE\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/\",\"url\":\"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/\",\"name\":\"Collettore 4-2-1 con catalizzatore | Aros Marmitte\",\"isPartOf\":{\"@id\":\"https:\/\/www.arosmarmitte.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.arosmarmitte.it\/wp-content\/uploads\/Collettore-di-scarico-4-2-1-con-catalizzatore-per-subaru-brz-toyota-GT86-manifold-headers-catalyst-exhuast-system-sound-echappement-marmitta-scarico-artigianale-1.jpg\",\"datePublished\":\"2024-10-02T19:52:05+00:00\",\"dateModified\":\"2024-10-02T19:52:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/#primaryimage\",\"url\":\"https:\/\/www.arosmarmitte.it\/wp-content\/uploads\/Collettore-di-scarico-4-2-1-con-catalizzatore-per-subaru-brz-toyota-GT86-manifold-headers-catalyst-exhuast-system-sound-echappement-marmitta-scarico-artigianale-1.jpg\",\"contentUrl\":\"https:\/\/www.arosmarmitte.it\/wp-content\/uploads\/Collettore-di-scarico-4-2-1-con-catalizzatore-per-subaru-brz-toyota-GT86-manifold-headers-catalyst-exhuast-system-sound-echappement-marmitta-scarico-artigianale-1.jpg\",\"width\":1200,\"height\":1093},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.arosmarmitte.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.arosmarmitte.it\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Collettore 4-2-1 con catalizzatore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.arosmarmitte.it\/en\/#website\",\"url\":\"https:\/\/www.arosmarmitte.it\/en\/\",\"name\":\"Aros Marmitte\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.arosmarmitte.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.arosmarmitte.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.arosmarmitte.it\/en\/#organization\",\"name\":\"AROS Marmitte\",\"alternateName\":\"AROS SRL\",\"url\":\"https:\/\/www.arosmarmitte.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.arosmarmitte.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.arosmarmitte.it\/wp-content\/uploads\/AROS_MARMITTE_LOGO_2016-EXHAUST-SYSTEMS-ECHAPPEMENT-SCARICO-ARTIGIANALE-MARMITTA-1-1.jpg\",\"contentUrl\":\"https:\/\/www.arosmarmitte.it\/wp-content\/uploads\/AROS_MARMITTE_LOGO_2016-EXHAUST-SYSTEMS-ECHAPPEMENT-SCARICO-ARTIGIANALE-MARMITTA-1-1.jpg\",\"width\":1000,\"height\":875,\"caption\":\"AROS Marmitte\"},\"image\":{\"@id\":\"https:\/\/www.arosmarmitte.it\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/arosmarmitte\",\"https:\/\/x.com\/AROS_MARMITTE\",\"https:\/\/www.instagram.com\/arosmarmitte\/\",\"https:\/\/www.tiktok.com\/@aros_marmitte\"],\"email\":\"info@arosmarmitte.it\",\"telephone\":\"3401417652\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Collettore 4-2-1 con catalizzatore | Aros Marmitte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/","og_locale":"en_US","og_type":"article","og_title":"Collettore 4-2-1 con catalizzatore","og_description":"Il collettore \u00e8 una parte fondamentale del sistema di scarico dell&#8217;auto in quanto \u00e8 il primo elemento che permette ai gas di evacuare dalla camera di scoppio, quindi l&#8217;installazione in vettura di un collettore dimensionato ad hoc e con spirito sportivo, consente di incrementare abbastanza agevolmente le prestazioni del motore. In questo caso la conformazione [&hellip;]","og_url":"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/","og_site_name":"Aros Marmitte","article_publisher":"https:\/\/www.facebook.com\/arosmarmitte","article_modified_time":"2024-10-02T19:52:07+00:00","og_image":[{"width":1200,"height":1093,"url":"https:\/\/www.arosmarmitte.it\/wp-content\/uploads\/Collettore-di-scarico-4-2-1-con-catalizzatore-per-subaru-brz-toyota-GT86-manifold-headers-catalyst-exhuast-system-sound-echappement-marmitta-scarico-artigianale-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AROS_MARMITTE","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/","url":"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/","name":"Collettore 4-2-1 con catalizzatore | Aros Marmitte","isPartOf":{"@id":"https:\/\/www.arosmarmitte.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/#primaryimage"},"image":{"@id":"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/#primaryimage"},"thumbnailUrl":"https:\/\/www.arosmarmitte.it\/wp-content\/uploads\/Collettore-di-scarico-4-2-1-con-catalizzatore-per-subaru-brz-toyota-GT86-manifold-headers-catalyst-exhuast-system-sound-echappement-marmitta-scarico-artigianale-1.jpg","datePublished":"2024-10-02T19:52:05+00:00","dateModified":"2024-10-02T19:52:07+00:00","breadcrumb":{"@id":"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/#primaryimage","url":"https:\/\/www.arosmarmitte.it\/wp-content\/uploads\/Collettore-di-scarico-4-2-1-con-catalizzatore-per-subaru-brz-toyota-GT86-manifold-headers-catalyst-exhuast-system-sound-echappement-marmitta-scarico-artigianale-1.jpg","contentUrl":"https:\/\/www.arosmarmitte.it\/wp-content\/uploads\/Collettore-di-scarico-4-2-1-con-catalizzatore-per-subaru-brz-toyota-GT86-manifold-headers-catalyst-exhuast-system-sound-echappement-marmitta-scarico-artigianale-1.jpg","width":1200,"height":1093},{"@type":"BreadcrumbList","@id":"https:\/\/www.arosmarmitte.it\/en\/prodotto\/exhaust-systems\/collettore-4-2-1-con-catalizzatore-8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arosmarmitte.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.arosmarmitte.it\/shop\/"},{"@type":"ListItem","position":3,"name":"Collettore 4-2-1 con catalizzatore"}]},{"@type":"WebSite","@id":"https:\/\/www.arosmarmitte.it\/en\/#website","url":"https:\/\/www.arosmarmitte.it\/en\/","name":"Aros Marmitte","description":"","publisher":{"@id":"https:\/\/www.arosmarmitte.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arosmarmitte.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arosmarmitte.it\/en\/#organization","name":"AROS Marmitte","alternateName":"AROS SRL","url":"https:\/\/www.arosmarmitte.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arosmarmitte.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.arosmarmitte.it\/wp-content\/uploads\/AROS_MARMITTE_LOGO_2016-EXHAUST-SYSTEMS-ECHAPPEMENT-SCARICO-ARTIGIANALE-MARMITTA-1-1.jpg","contentUrl":"https:\/\/www.arosmarmitte.it\/wp-content\/uploads\/AROS_MARMITTE_LOGO_2016-EXHAUST-SYSTEMS-ECHAPPEMENT-SCARICO-ARTIGIANALE-MARMITTA-1-1.jpg","width":1000,"height":875,"caption":"AROS Marmitte"},"image":{"@id":"https:\/\/www.arosmarmitte.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arosmarmitte","https:\/\/x.com\/AROS_MARMITTE","https:\/\/www.instagram.com\/arosmarmitte\/","https:\/\/www.tiktok.com\/@aros_marmitte"],"email":"info@arosmarmitte.it","telephone":"3401417652"}]}},"_links":{"self":[{"href":"https:\/\/www.arosmarmitte.it\/en\/wp-json\/wp\/v2\/product\/126316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arosmarmitte.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.arosmarmitte.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arosmarmitte.it\/en\/wp-json\/wp\/v2\/comments?post=126316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arosmarmitte.it\/en\/wp-json\/wp\/v2\/media\/111943"}],"wp:attachment":[{"href":"https:\/\/www.arosmarmitte.it\/en\/wp-json\/wp\/v2\/media?parent=126316"}],"wp:term":[{"taxonomy":"marca","embeddable":true,"href":"https:\/\/www.arosmarmitte.it\/en\/wp-json\/wp\/v2\/marca?post=126316"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.arosmarmitte.it\/en\/wp-json\/wp\/v2\/product_brand?post=126316"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.arosmarmitte.it\/en\/wp-json\/wp\/v2\/product_cat?post=126316"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.arosmarmitte.it\/en\/wp-json\/wp\/v2\/product_tag?post=126316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}